{"id":4556,"date":"2019-01-16T10:44:15","date_gmt":"2019-01-16T10:44:15","guid":{"rendered":"https:\/\/www.igengineering.it\/ita\/?page_id=4556"},"modified":"2019-01-16T10:46:38","modified_gmt":"2019-01-16T10:46:38","slug":"geometra-magri-innocente","status":"publish","type":"page","link":"https:\/\/www.igengineering.it\/ita\/geometra-magri-innocente\/","title":{"rendered":"Geometra Magri Innocente"},"content":{"rendered":"<p>Alcuni lavori realizzati dal Geom. Magri Innocente:<\/p>\n<ul>\n<li>Costruzione della Centrale Nucleare di Bagdad, dal 1978 al 1980, di cui non \u00e8 possibile avere immagini e certificazioni in quanto luogo strategico;<\/li>\n<li>Con l\u2019impresa Foster di Milano, un complesso commerciale in Costa d\u2019Avorio;<\/li>\n<li>Con l\u2019impresa Foster e Snia un gasdotto in Yemen;<\/li>\n<li>Partecipazione con l\u2019impresa Pizzarotti SpA, leader italiano nel settore, all\u2019esecuzione dell\u2019aereoporto De Gaulles di Parigi;<\/li>\n<li>Con l\u2019impresa Gabassi, costruzione del Forum di Assago a Milano;<\/li>\n<li>Realizzazione e manutenzione di tratti ferroviari stradali con Ferrovie Nord in collaborazione con l\u2019impresa A.C.V.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Alcuni lavori realizzati dal Geom. Magri Innocente: Costruzione della Centrale Nucleare di Bagdad, dal 1978 al 1980, di cui non \u00e8 possibile avere immagini e certificazioni in quanto luogo strategico; Con l\u2019impresa Foster di Milano, un complesso commerciale in Costa d\u2019Avorio; Con l\u2019impresa Foster e Snia un gasdotto in Yemen; Partecipazione con l\u2019impresa Pizzarotti SpA, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4556","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.igengineering.it\/ita\/wp-json\/wp\/v2\/pages\/4556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.igengineering.it\/ita\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.igengineering.it\/ita\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.igengineering.it\/ita\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.igengineering.it\/ita\/wp-json\/wp\/v2\/comments?post=4556"}],"version-history":[{"count":2,"href":"https:\/\/www.igengineering.it\/ita\/wp-json\/wp\/v2\/pages\/4556\/revisions"}],"predecessor-version":[{"id":4558,"href":"https:\/\/www.igengineering.it\/ita\/wp-json\/wp\/v2\/pages\/4556\/revisions\/4558"}],"wp:attachment":[{"href":"https:\/\/www.igengineering.it\/ita\/wp-json\/wp\/v2\/media?parent=4556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}